{"id":2006,"date":"2016-05-12T15:26:46","date_gmt":"2016-05-12T13:26:46","guid":{"rendered":"http:\/\/chitarrafacile.com\/accordichitarra\/?p=2006"},"modified":"2016-05-12T15:26:46","modified_gmt":"2016-05-12T13:26:46","slug":"accordi-chitarra-firth-of-fifth-genesis","status":"publish","type":"post","link":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/","title":{"rendered":"Accordi Chitarra: Firth Of Fifth, Genesis"},"content":{"rendered":"<p><strong>Accordi Chitarra<\/strong>: ecco gli accordi di chitarra per suonare\u00a0<strong>Firth of fifth <\/strong>di\u00a0<em>Genesis.<\/em><\/p>\n<p>Gli accordi di chitarra presenti in questa canzone sono:\u00a0<a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-si\/\" target=\"_blank\">SI<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-la\/\" target=\"_blank\">LA 6\/9<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-mi\/\" target=\"_blank\">MI\/SOL#<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-mi\/\" target=\"_blank\">MI-\/SOL#<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-fa\/\" target=\"_blank\">FA#-7<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-fa\/\" target=\"_blank\">FA#-<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-si\/\" target=\"_blank\">SIsus4<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-si\/\" target=\"_blank\">SI7<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-mi\/\" target=\"_blank\">MI<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-fa\/\" target=\"_blank\">FA#-7\/MI<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-si\/\" target=\"_blank\">SI-\/RE<\/a>,\u00a0 <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-do\/\" target=\"_blank\">DO+7\/RE<\/a>,\u00a0 <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-sol\/\" target=\"_blank\">SOL<\/a>,\u00a0 <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-si\/\" target=\"_blank\">SIb dim<\/a>,\u00a0 <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-la\/\" target=\"_blank\">LA<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-mi\/\" target=\"_blank\">MI+7<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-si\/\" target=\"_blank\">SIb-<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-mi\/\" target=\"_blank\">MIb-<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-si\/\" target=\"_blank\">SIb7<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-mi\/\" target=\"_blank\">MIb<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-mi\/\" target=\"_blank\">MIb\/FA<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-fa\/\" target=\"_blank\">FA<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-si\/\" target=\"_blank\">SIb\/DO<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-do\/\" target=\"_blank\">DO-\/FA<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-mi\/\" target=\"_blank\">MI6<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-do\/\" target=\"_blank\">DO#-7\/FA#<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-mi\/\" target=\"_blank\">MI-\/SOL<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-la\/\" target=\"_blank\">LAsus4<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-re\/\" target=\"_blank\">RE<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-do\/\" target=\"_blank\">DO#-7<\/a>, <a href=\"http:\/\/chitarrafacile.com\/accordichitarra\/accordi-chitarra-fa\/\" target=\"_blank\">FA#<\/a>.<\/p>\n<p>Clicca sui nomi degli accordi di chitarra qui sopra per vedere come si fanno, nel caso non lo sapessi.<\/p>\n<p>Se non sai ancora suonare la chitarra e vuoi imparare la tua prima canzone puoi scaricare le lezioni di chitarra gratuite di base per partire da zero ed imparare la tua prima canzone in 10 giorni\u00a0<a href=\"http:\/\/suonarechitarra.com\/offerte\/lezioni-di-chitarra-5\/\">cliccando qui<\/a>.<\/p>\n<p><strong>Firth Of Fifth<\/strong> \u00e8 una canzone incisa nel <strong>1973<\/strong> dai <strong>Genesis<\/strong> che prende il proprio nome dalla storpiatura dell\u2019estuario del fiume Forth (Scozia), conosciuto come \u201cFirth Of Forth\u201d. E\u2019 una delle canzoni pi\u00f9 rappresentative del <strong>rock progressivo<\/strong> dei Genesis nonch\u00e8 <strong>uno dei pi\u00f9 famosi<\/strong> tra i loro primi lavori.<br \/>\nE\u2019 stata composta dal <strong>tastierista Tony Banks<\/strong>, che assieme a <strong>Mike Rutherford<\/strong> ne ha anche redatto il testo (definito dallo stesso Banks \u201cuno dei peggiori con cui abbia mai avuto a che fare\u201d).<br \/>\nE\u2019 stata rivista anche in versione solo strumentale per i loro tour <em>We Can\u2019t Dance<\/em> (1992), <em>Calling All Stations<\/em> (1998) e <em>Turn It On Again<\/em> (2007) ed anche il <strong>chitarrista Steve Hackett<\/strong> ne ha reinterpretata una versione per il suo album solista <em>Watcher Of The Skies <\/em>(1997).<\/p>\n<p>Qui di seguito puoi vedere il video del brano di Genesis, Firth of fifth:<\/p>\n<p><iframe width=\"680\" height=\"510\" src=\"https:\/\/www.youtube.com\/embed\/t7-qJ0afB_4?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<p>Ecco invece qui di seguito gli <strong>accordi di chitarra<\/strong> per suonare il brano:<\/p>\n<pre>SI\r\n\r\nThe path is clear\r\n\r\nLA 6\/9\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 MI\/SOL#\r\n\r\nThough no eyes can see\r\n\r\nSI\u00a0\u00a0 MIm\/SOL#\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 FA#m7 FA#m\u00a0\u00a0 SIsus4\u00a0 SI7\r\n\r\nThe course laid down long\u00a0 be\u00a0\u00a0 fore.\r\n\r\nMI\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 FA#m7\/MI\r\n\r\nAnd so with gods and men\r\n\r\nSIm\/RE\u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0DOmaj7\/RE\r\n\r\nThe sheep remain inside their pen,\r\n\r\nSOL \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0MI\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SIb dim\r\n\r\nThough many times they've seen the way to leave.\r\n\r\nRIPETI:\r\n\r\n||:\r\n\r\nHe rides majestic\r\n\r\nPast homes of men\r\n\r\nWho care not or gaze with joy,\r\n\r\nTo see reflected there\r\n\r\nThe trees, the sky, the lily fair,\r\n\r\nThe scene of death is lying just below.\r\n\r\n:||\r\n\r\nMI\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 LA\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 MImaj7\u00a0\u00a0\u00a0\u00a0 LA\r\n\r\nThe mountains cuts off the town from view,\r\n\r\nSIbm\u00a0\u00a0\u00a0\u00a0 MIbm\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SIb7\u00a0\u00a0 MIb\r\n\r\nLike a cancer growth is removed by skill.\r\n\r\nMIb\/FA FA\u00a0\u00a0 SOL\r\n\r\nLet it be\u00a0\u00a0 re\u00a0 vealed.\r\n\r\nSIb\/DO\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 DOm\/FA\r\n\r\nA waterfall, his madrigal.\r\n\r\nMI6\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SI\r\n\r\nAn inland sea, his symphony.\r\n\r\nMI6 SI DO#m7\/FA#\r\n\r\nSI\r\n\r\nUndinal songs\r\n\r\nLA 6\/9\u00a0\u00a0\u00a0\u00a0 MI\/SOL#\r\n\r\nUrge the sailors on\r\n\r\nSI\u00a0\u00a0\u00a0 MIm\/SOL\u00a0\u00a0\u00a0\u00a0 LAsus4\u00a0\u00a0 RE\u00a0\u00a0\u00a0 DO#m7 FA#\r\n\r\nTill lured by sirens' cry.\r\n\r\nNow as the river dissolves in sea,\r\n\r\nSo Neptune has claimed another soul.\r\n\r\nAnd so with gods and men\r\n\r\nThe sheep remain inside their pen,\r\n\r\nUntil the Shepherd leads his flock away.\r\n\r\nThe sands of time were eroded by\r\n\r\nThe river of constant change.\r\n<\/pre>\n<p>\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014\u2014<\/p>\n<p>Se non sai ancora suonare la chitarra e vuoi imparare la tua prima canzone puoi scaricare le <a href=\"http:\/\/suonarechitarra.com\/offerte\/lezioni-di-chitarra-5\/\">lezioni di chitarra gratuite<\/a> di base per partire da zero ed imparare la tua prima canzone in 10 giorni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Accordi Chitarra: ecco gli accordi di chitarra per suonare\u00a0Firth of fifth di\u00a0Genesis. Gli accordi di chitarra presenti in questa canzone sono:\u00a0SI, LA 6\/9, MI\/SOL#, MI-\/SOL#, FA#-7, FA#-, SIsus4, SI7, MI, FA#-7\/MI, SI-\/RE,\u00a0 DO+7\/RE,\u00a0 SOL,\u00a0 SIb dim,\u00a0 LA, MI+7, SIb-, MIb-, SIb7, MIb, MIb\/FA, FA, SIb\/DO, DO-\/FA, MI6, DO#-7\/FA#, MI-\/SOL, LAsus4, RE, DO#-7, FA#. Clicca sui nomi degli accordi di chitarra qui sopra per vedere come si fanno, nel caso non lo sapessi. Se non sai ancora suonare la chitarra e vuoi imparare la tua prima canzone puoi scaricare le lezioni di chitarra gratuite di base per partire da zero ed <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[261],"class_list":["post-2006","post","type-post","status-publish","format-standard","hentry","category-accordi-canzoni","tag-genesis"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.8 - aioseo.com -->\n\t<meta name=\"description\" content=\"Accordi Chitarra: ecco gli accordi di chitarra per suonare Firth of fifth di Genesis. Gli accordi di chitarra presenti in questa canzone sono: SI, LA 6\/9, MI\/SOL#, MI-\/SOL#, FA#-7, FA#-, SIsus4, SI7, MI, FA#-7\/MI, SI-\/RE, DO+7\/RE, SOL, SIb dim, LA, MI+7, SIb-, MIb-, SIb7, MIb, MIb\/FA, FA, SIb\/DO, DO-\/FA, MI6, DO#-7\/FA#, MI-\/SOL, LAsus4, RE, DO#-7, FA#. Clicca sui\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"David Carelse\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.8\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Accordi Chitarra | Tutti gli accordi di chitarra\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Accordi Chitarra: Firth Of Fifth, Genesis\" \/>\n\t\t<meta property=\"og:description\" content=\"Accordi Chitarra: ecco gli accordi di chitarra per suonare Firth of fifth di Genesis. Gli accordi di chitarra presenti in questa canzone sono: SI, LA 6\/9, MI\/SOL#, MI-\/SOL#, FA#-7, FA#-, SIsus4, SI7, MI, FA#-7\/MI, SI-\/RE, DO+7\/RE, SOL, SIb dim, LA, MI+7, SIb-, MIb-, SIb7, MIb, MIb\/FA, FA, SIb\/DO, DO-\/FA, MI6, DO#-7\/FA#, MI-\/SOL, LAsus4, RE, DO#-7, FA#. Clicca sui\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-05-12T13:26:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-05-12T13:26:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Accordi Chitarra: Firth Of Fifth, Genesis\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Accordi Chitarra: ecco gli accordi di chitarra per suonare Firth of fifth di Genesis. Gli accordi di chitarra presenti in questa canzone sono: SI, LA 6\/9, MI\/SOL#, MI-\/SOL#, FA#-7, FA#-, SIsus4, SI7, MI, FA#-7\/MI, SI-\/RE, DO+7\/RE, SOL, SIb dim, LA, MI+7, SIb-, MIb-, SIb7, MIb, MIb\/FA, FA, SIb\/DO, DO-\/FA, MI6, DO#-7\/FA#, MI-\/SOL, LAsus4, RE, DO#-7, FA#. Clicca sui\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/#article\",\"name\":\"Accordi Chitarra: Firth Of Fifth, Genesis\",\"headline\":\"Accordi Chitarra: Firth Of Fifth, Genesis\",\"author\":{\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/author\\\/david\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/#organization\"},\"datePublished\":\"2016-05-12T15:26:46+02:00\",\"dateModified\":\"2016-05-12T15:26:46+02:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/#webpage\"},\"articleSection\":\"Accordi Canzoni, Genesis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/category\\\/accordi-canzoni\\\/#listItem\",\"name\":\"Accordi Canzoni\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/category\\\/accordi-canzoni\\\/#listItem\",\"position\":2,\"name\":\"Accordi Canzoni\",\"item\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/category\\\/accordi-canzoni\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/#listItem\",\"name\":\"Accordi Chitarra: Firth Of Fifth, Genesis\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/#listItem\",\"position\":3,\"name\":\"Accordi Chitarra: Firth Of Fifth, Genesis\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/category\\\/accordi-canzoni\\\/#listItem\",\"name\":\"Accordi Canzoni\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/#organization\",\"name\":\"Accordi Chitarra\",\"description\":\"Tutti gli accordi di chitarra\",\"url\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/author\\\/david\\\/#author\",\"url\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/author\\\/david\\\/\",\"name\":\"David Carelse\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/614189bda2c19cf85ec329f346021c5909bcb3407d39cad5c506a9e2a1cd79ba?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"David Carelse\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/#webpage\",\"url\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/\",\"name\":\"Accordi Chitarra: Firth Of Fifth, Genesis\",\"description\":\"Accordi Chitarra: ecco gli accordi di chitarra per suonare Firth of fifth di Genesis. Gli accordi di chitarra presenti in questa canzone sono: SI, LA 6\\\/9, MI\\\/SOL#, MI-\\\/SOL#, FA#-7, FA#-, SIsus4, SI7, MI, FA#-7\\\/MI, SI-\\\/RE, DO+7\\\/RE, SOL, SIb dim, LA, MI+7, SIb-, MIb-, SIb7, MIb, MIb\\\/FA, FA, SIb\\\/DO, DO-\\\/FA, MI6, DO#-7\\\/FA#, MI-\\\/SOL, LAsus4, RE, DO#-7, FA#. Clicca sui\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/2016\\\/05\\\/12\\\/accordi-chitarra-firth-of-fifth-genesis\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/author\\\/david\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/author\\\/david\\\/#author\"},\"datePublished\":\"2016-05-12T15:26:46+02:00\",\"dateModified\":\"2016-05-12T15:26:46+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/#website\",\"url\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/\",\"name\":\"Accordi Chitarra\",\"description\":\"Tutti gli accordi di chitarra\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/chitarrafacile.com\\\/accordichitarra\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Accordi Chitarra: Firth Of Fifth, Genesis","description":"Accordi Chitarra: ecco gli accordi di chitarra per suonare Firth of fifth di Genesis. Gli accordi di chitarra presenti in questa canzone sono: SI, LA 6\/9, MI\/SOL#, MI-\/SOL#, FA#-7, FA#-, SIsus4, SI7, MI, FA#-7\/MI, SI-\/RE, DO+7\/RE, SOL, SIb dim, LA, MI+7, SIb-, MIb-, SIb7, MIb, MIb\/FA, FA, SIb\/DO, DO-\/FA, MI6, DO#-7\/FA#, MI-\/SOL, LAsus4, RE, DO#-7, FA#. Clicca sui","canonical_url":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/#article","name":"Accordi Chitarra: Firth Of Fifth, Genesis","headline":"Accordi Chitarra: Firth Of Fifth, Genesis","author":{"@id":"https:\/\/chitarrafacile.com\/accordichitarra\/author\/david\/#author"},"publisher":{"@id":"https:\/\/chitarrafacile.com\/accordichitarra\/#organization"},"datePublished":"2016-05-12T15:26:46+02:00","dateModified":"2016-05-12T15:26:46+02:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/#webpage"},"isPartOf":{"@id":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/#webpage"},"articleSection":"Accordi Canzoni, Genesis"},{"@type":"BreadcrumbList","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chitarrafacile.com\/accordichitarra#listItem","position":1,"name":"Home","item":"https:\/\/chitarrafacile.com\/accordichitarra","nextItem":{"@type":"ListItem","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/category\/accordi-canzoni\/#listItem","name":"Accordi Canzoni"}},{"@type":"ListItem","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/category\/accordi-canzoni\/#listItem","position":2,"name":"Accordi Canzoni","item":"https:\/\/chitarrafacile.com\/accordichitarra\/category\/accordi-canzoni\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/#listItem","name":"Accordi Chitarra: Firth Of Fifth, Genesis"},"previousItem":{"@type":"ListItem","@id":"https:\/\/chitarrafacile.com\/accordichitarra#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/#listItem","position":3,"name":"Accordi Chitarra: Firth Of Fifth, Genesis","previousItem":{"@type":"ListItem","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/category\/accordi-canzoni\/#listItem","name":"Accordi Canzoni"}}]},{"@type":"Organization","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/#organization","name":"Accordi Chitarra","description":"Tutti gli accordi di chitarra","url":"https:\/\/chitarrafacile.com\/accordichitarra\/"},{"@type":"Person","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/author\/david\/#author","url":"https:\/\/chitarrafacile.com\/accordichitarra\/author\/david\/","name":"David Carelse","image":{"@type":"ImageObject","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/614189bda2c19cf85ec329f346021c5909bcb3407d39cad5c506a9e2a1cd79ba?s=96&d=mm&r=g","width":96,"height":96,"caption":"David Carelse"}},{"@type":"WebPage","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/#webpage","url":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/","name":"Accordi Chitarra: Firth Of Fifth, Genesis","description":"Accordi Chitarra: ecco gli accordi di chitarra per suonare Firth of fifth di Genesis. Gli accordi di chitarra presenti in questa canzone sono: SI, LA 6\/9, MI\/SOL#, MI-\/SOL#, FA#-7, FA#-, SIsus4, SI7, MI, FA#-7\/MI, SI-\/RE, DO+7\/RE, SOL, SIb dim, LA, MI+7, SIb-, MIb-, SIb7, MIb, MIb\/FA, FA, SIb\/DO, DO-\/FA, MI6, DO#-7\/FA#, MI-\/SOL, LAsus4, RE, DO#-7, FA#. Clicca sui","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/chitarrafacile.com\/accordichitarra\/#website"},"breadcrumb":{"@id":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/#breadcrumblist"},"author":{"@id":"https:\/\/chitarrafacile.com\/accordichitarra\/author\/david\/#author"},"creator":{"@id":"https:\/\/chitarrafacile.com\/accordichitarra\/author\/david\/#author"},"datePublished":"2016-05-12T15:26:46+02:00","dateModified":"2016-05-12T15:26:46+02:00"},{"@type":"WebSite","@id":"https:\/\/chitarrafacile.com\/accordichitarra\/#website","url":"https:\/\/chitarrafacile.com\/accordichitarra\/","name":"Accordi Chitarra","description":"Tutti gli accordi di chitarra","inLanguage":"it-IT","publisher":{"@id":"https:\/\/chitarrafacile.com\/accordichitarra\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Accordi Chitarra | Tutti gli accordi di chitarra","og:type":"article","og:title":"Accordi Chitarra: Firth Of Fifth, Genesis","og:description":"Accordi Chitarra: ecco gli accordi di chitarra per suonare Firth of fifth di Genesis. Gli accordi di chitarra presenti in questa canzone sono: SI, LA 6\/9, MI\/SOL#, MI-\/SOL#, FA#-7, FA#-, SIsus4, SI7, MI, FA#-7\/MI, SI-\/RE, DO+7\/RE, SOL, SIb dim, LA, MI+7, SIb-, MIb-, SIb7, MIb, MIb\/FA, FA, SIb\/DO, DO-\/FA, MI6, DO#-7\/FA#, MI-\/SOL, LAsus4, RE, DO#-7, FA#. Clicca sui","og:url":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/","article:published_time":"2016-05-12T13:26:46+00:00","article:modified_time":"2016-05-12T13:26:46+00:00","twitter:card":"summary_large_image","twitter:title":"Accordi Chitarra: Firth Of Fifth, Genesis","twitter:description":"Accordi Chitarra: ecco gli accordi di chitarra per suonare Firth of fifth di Genesis. Gli accordi di chitarra presenti in questa canzone sono: SI, LA 6\/9, MI\/SOL#, MI-\/SOL#, FA#-7, FA#-, SIsus4, SI7, MI, FA#-7\/MI, SI-\/RE, DO+7\/RE, SOL, SIb dim, LA, MI+7, SIb-, MIb-, SIb7, MIb, MIb\/FA, FA, SIb\/DO, DO-\/FA, MI6, DO#-7\/FA#, MI-\/SOL, LAsus4, RE, DO#-7, FA#. Clicca sui"},"aioseo_meta_data":{"post_id":"2006","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-19 05:39:51","updated":"2026-03-27 09:45:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chitarrafacile.com\/accordichitarra\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chitarrafacile.com\/accordichitarra\/category\/accordi-canzoni\/\" title=\"Accordi Canzoni\">Accordi Canzoni<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAccordi Chitarra: Firth Of Fifth, Genesis\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/chitarrafacile.com\/accordichitarra"},{"label":"Accordi Canzoni","link":"https:\/\/chitarrafacile.com\/accordichitarra\/category\/accordi-canzoni\/"},{"label":"Accordi Chitarra: Firth Of Fifth, Genesis","link":"https:\/\/chitarrafacile.com\/accordichitarra\/2016\/05\/12\/accordi-chitarra-firth-of-fifth-genesis\/"}],"_links":{"self":[{"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/posts\/2006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/comments?post=2006"}],"version-history":[{"count":1,"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/posts\/2006\/revisions"}],"predecessor-version":[{"id":2007,"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/posts\/2006\/revisions\/2007"}],"wp:attachment":[{"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/media?parent=2006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/categories?post=2006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chitarrafacile.com\/accordichitarra\/wp-json\/wp\/v2\/tags?post=2006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}