{"id":471,"date":"2021-03-30T18:31:00","date_gmt":"2021-03-30T16:31:00","guid":{"rendered":"https:\/\/chitarrafacile.com\/lezionidichitarra\/?p=471"},"modified":"2022-11-04T10:20:06","modified_gmt":"2022-11-04T09:20:06","slug":"6-consigli-per-creare-un-bel-suono-di-chitarra","status":"publish","type":"post","link":"https:\/\/chitarrafacile.com\/lezionidichitarra\/6-consigli-per-creare-un-bel-suono-di-chitarra\/","title":{"rendered":"6 Consigli per Creare Suoni di Chitarra Pazzeschi"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In questo video ho raccolto 6 dei consigli sulla creazione del suono della chitarra che ho ricevuto negli anni e che mi hanno fatto dire &#8220;<em>Ma come ho fatto a non pensarci prima?<\/em>&#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consigli semplici, ma geniali che ti aiuteranno a gestire meglio gli <strong>effetti per chitarra<\/strong>:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"6 TRUCCHI PER CREARE SUONI PAZZESCHI | lezioni di chitarra\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/WhqLBV7Gcrw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Scopri il corso &#8220;Che Suono!&#8221; e comincia a creare dei suoni di alto livello: <a href=\"https:\/\/chitarrafacile.com\/chesuono\" title=\"clicca qui.\">clicca qui.<\/a><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Guida base agli effetti per chitarra<\/strong>:\u00a0<a href=\"https:\/\/chitarrafacile.com\/effetti-chitarra\/\">clicca qui per scaricarla gratuitamente.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unisciti alla&nbsp;<strong>community<\/strong>&nbsp;degli Strimpellari,&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/groups\/suonarechitarra\/\" target=\"_blank\">clicca qui.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per&nbsp;<strong>imparare, o migliorare a suonare<\/strong>&nbsp;la chitarra e vedere tutti i nostri corsi,&nbsp;<a rel=\"noreferrer noopener\" href=\"http:\/\/chitarrafacile.com\/corsi\/\" target=\"_blank\">clicca qui.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Introduzione<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Ma certo, come ho fatto a non pensarci prima?<\/em>&#8220;<br>Ecco, questo \u00e8 quello che mi sono detto nel corso degli anni, ogni volta che qualcuno mi mostrava uno di questi trucchi sugli <strong>effetti per chitarra<\/strong>. O meglio, pi\u00f9 che trucchi sono idee semplici ma geniali. In questo video quindi vediamo 6 &#8220;best practices\u201d o consigli che possono aiutarti a creare un bel suono pi\u00f9 velocemente, o a gestire gli effetti in modo pi\u00f9 efficace per creare dei suoni migliori.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelli che vedremo oggi sono trucchi che io ho accumulato nel corso degli anni, soprattutto all\u2019inizio. Il primo dei trucchi che vedremo, in realt\u00e0, \u00e8 una cosa che ho scoperto recentemente, che non avevo mai fatto prima, per\u00f2 di fatto sono tutti consigli abbastanza semplici.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Penso che un chitarrista esperto non abbia molto da imparare da questo video. Per chi ha iniziato a gestire gli effetti o creare dei suoni da poco, invece, questi consigli potrebbero aiutarvi a rendere pi\u00f9 veloce il processo di creazione del suono oppure a generare suoni di maggiore impatto e qualit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Altra cosa importante: io per una questione pratica utilizzer\u00f2 il Fractal, per farvi vedere a video come vado a gestire il suono, ma di fatto tutto quello che vedremo in questo video si potr\u00e0 applicare anche a qualsiasi altro sistema, ad esempio ad un amplificatore con dei pedalini fisici.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consiglio #1<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Come ho detto prima \u00e8 quello che ho scoperto pi\u00f9 recentemente. Quest\u2019idea render\u00e0 pi\u00f9 veloce lo sviluppo e la creazione dei suoni, come spiegato da <strong><em>Cooper Carter<\/em><\/strong> che, nel caso non conosciate, vi consiglio di seguire: oltre ad utilizzare Fractal, motivo per cui ho seguito delle sue Masterclass, ha collaborato con <strong><em>Steve Vai<\/em><\/strong>, i <strong><em>Coldplay<\/em><\/strong> e altri artisti di fama mondiale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019idea consiste nel posizionare un looper, o una <strong>loop station<\/strong>, all\u2019inizio della nostra catena, cos\u00ec da poter registrare una breve traccia e poterla mettere in loop. Questa tecnica pu\u00f2 essere utilizzata con un qualsiasi looper a vostra disposizione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quindi, subito dopo la chitarra e prima di qualsiasi altro routing, abbiamo il nostro looper e andiamo a registrare una piccola traccia audio: a questo punto, se registro con un amplificatore in canale lead, io sento la riproduzione del loop con un suono distorto, perch\u00e9 questo \u00e8 il suono della mia strumentazione. Ma cosa accadrebbe se dovessi andare a richiamare un altro amplificatore col Fractal? O se in analogico andassi a cambiare amplificatore o canale dello stesso? Non \u00e8 pi\u00f9 necessario andare a suonare continuamente, posso sentire in diretta la stessa traccia registrata precedentemente con il suono che viene modificato dall&#8217;equipaggiamento che ci inserisco dopo. Questo \u00e8 importantissimo perch\u00e9 suonando dal \u201cvivo\u201d per ogni amplificatore, potrebbe capitare che io cambi leggermente il mio modo di suonare, e cos\u00ec anche il suono.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel caso utilizzassi un software come nel mio caso, potrei dedicarmi semplicemente a provare i vari settaggi, nel caso fossi in analogico potrei semplicemente cambiare i cavi, gli effetti, i settaggi degli stessi o l&#8217;amplificatore. Quindi ecco perch\u00e9 \u00e8 importantissimo metterlo all\u2019inizio della nostra catena, per creare dei suoni senza dover suonare ogni volta \u201cda capo&#8221;. Il contro \u00e8 che evitando di suonare in prima persona mentre provo i vari setting, non sentirei il &#8220;<em><strong>suono sotto le dita<\/strong><\/em>&#8221; cosa estremamente personale per noi chitarristi, in quanto ci permette di capire pi\u00f9 facilmente l\u2019attacco del suono e molti altri aspetti che ci possono far sentire o meno a nostro agio durante un&#8217;esecuzione. A livello di mix e qualit\u00e0 del suono non \u00e8 direttamente correlato, ma se noi ci troviamo bene a suonare, cambia anche il risultato della nostra esecuzione.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consiglio #2<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Durante gli anni, su questo canale, abbiamo parlato numerose volte con <strong><em>Marco Fanton<\/em><\/strong> di questo trucchetto: paragonare il nostro suono con un riferimento che ci piaccia, pi\u00f9 precisamente con la traccia isolata della chitarra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facciamo un esempio pratico: mi piace il suono di chitarra di \u201cRosanna\u201d dei Toto, cerco quindi la traccia isolata (posso scrivere su YouTube il titolo del brano e aggiungere in seguire &#8220;isolated track&#8221; oppure &#8220;guitar&#8221;) e vado a sentire il suono della sola chitarra. Questo \u00e8 utile perch\u00e9 alle volte all\u2019interno di un brano sentiamo frequenze anche di altri strumenti: tastiera, basso, ecc&#8230; In questo modo, se ci piace il suono della sola chitarra, avremo un riferimento verso cui tendere, arrangiando o aggiungendo frequenze che ci facciano assomigliare maggiormente alla traccia di riferimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questa cosa \u00e8 fondamentale anche per un altro motivo. Ascoltando a lungo il suono che vogliamo modificare, che sia con le cuffie o no, le nostre orecchie si stancheranno e satureranno, ovvero si abitueranno al suono mandandoci fuori dal nostro obiettivo. Con una traccia di riferimento riusciremo sempre a correggere la nostra rotta in modo pi\u00f9 oggettivo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consiglio #3<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Molto spesso nei live si utilizza un <strong>boost<\/strong> per aumentare il proprio volume durante gli assoli. Il trucco qui sta nell&#8217;utilizzare un <strong><em>equalizzatore<\/em><\/strong> al posto del boost per bucare meglio il mix senza necessariamente alzare il volume. Anche tenendo il volume a 0 db, riusciamo ad ottenere un suono che esce dal mix del gruppo e che si sente in modo chiaro. Non abbiamo alzato il volume, bens\u00ec abbiamo aumentato la presenza delle frequenze medie, frequenze caratteristiche della chitarra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quindi, utilizzando un&#8217;equalizzazione con forma ad \u201cA\u201d con la punta massima intorno ad 1 khz (eventualmente anche attorno ai 2 khz), ottengo questo risultato. Quest\u2019idea l\u2019ho vista spiegata per la prima volta dal grande Paul Gilbert. Se andassimo ad aumentare tutte le frequenze rischieremmo di creare confusione andandoci a sovrapporre ad altri strumenti.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo risultato l\u2019ho ottenuto posizionando l\u2019equalizzatore dopo il tutto il sistema di amplificazione (come in studio di registrazione), nel caso lo posizionassi prima la differenza si sentirebbe meno netta, in quanto andrei a saturare eccessivamente il preamplificatore, aumentando il livello di distorsione. In questo caso dovrei accentuare ulteriormente la curva dell\u2019equalizzatore e aumentare i db generali.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consiglio #4<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Questo consiglio \u00e8 molto semplice ma essendo controintuitivo, pochi chitarristi lo scoprono da soli: possiamo utilizzare due effetti identici, o della stessa famiglia, in serie: su un canale clean ho aggiunto due TS808, di cui uno modificato: il primo avr\u00e0 il drive a 2, il secondo a 4. L\u2019effetto che otteniamo \u00e8 ben diverso da un overdrive settato a 6, inoltre ci permette di poter giocare e di poter scolpire il nostro suono con pi\u00f9 precisione avendo molte sfumature a nostra disposizione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il primo dei due overdrive sar\u00e0 estremamente dinamico, sentiremo distorsione solo \u201cpicchiando\u201d con la mano, ma render\u00e0 caratteristico a livello timbrico il suono.Il secondo overdrive, invece, avr\u00e0 pi\u00f9 distorsione e saturer\u00e0 maggiormente. Con due overdrive possiamo quindi ottenere una sonorit\u00e0 tipica di un vero e proprio distorsore, ma con maggior dinamica ed un suono pi\u00f9 &#8220;rotondo&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consiglio #5<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il quinto consiglio consiste nell\u2019utilizzare il <strong><em>tremolo<\/em><\/strong> per gli arpeggi o note lunghe. Spesso vediamo chitarristi utilizzare la leva del vibrato o \u201cpiegare\u201d il manico per modificare un suono &#8220;troppo dritto&#8221; su arpeggi lunghi, perch\u00e9 noi chitarristi non riusciamo a lasciare una nota troppo a lungo senza modificarla!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizzando il tremolo potremo tranquillamente lasciare andare la nota, in quanto sar\u00e0 l\u2019effetto stesso a modificarla. Fai anche caso a quanto risulti ricco e completo il suono aggiungendo anche gli ambienti, come Delay e riverbero.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consiglio #6<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Questo consiglio \u00e8 semplicemente geniale: utilizzare il noise del nostro segnale per settare una <strong><em>modulazione<\/em><\/strong>: se aggiungessi un flanger al mio Rig e, con una distorsione importante, togliessi il noise gate, sentirei tutto il rumore di fondo del segnale: su questo rumore di fondo sentirei la modulazione in azione e potrai quindi modificare, senza dover suonare, la lunghezza d\u2019onda e la velocit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bene, questi erano i 6 consigli a cui magari non avevi pensato prima e che potrebbero aiutarti a creare suoni migliori o a crearli pi\u00f9 in fretta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In questo video ho raccolto 6 dei consigli sulla creazione del suono della chitarra che ho ricevuto negli anni e che mi hanno fatto dire &#8220;Ma come ho fatto a non pensarci prima?&#8220;. Consigli semplici, ma geniali che ti aiuteranno a gestire meglio gli effetti per chitarra: Scopri il corso &#8220;Che Suono!&#8221; e comincia a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-suoni-ed-effetti"],"_links":{"self":[{"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/posts\/471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/comments?post=471"}],"version-history":[{"count":5,"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/posts\/471\/revisions"}],"predecessor-version":[{"id":1156,"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/posts\/471\/revisions\/1156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/media\/481"}],"wp:attachment":[{"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/media?parent=471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/categories?post=471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chitarrafacile.com\/lezionidichitarra\/wp-json\/wp\/v2\/tags?post=471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}